{"id":9665,"date":"2021-09-23T03:28:10","date_gmt":"2021-09-23T03:28:10","guid":{"rendered":"https:\/\/www.valide-lab.com\/about\/"},"modified":"2026-01-27T13:52:58","modified_gmt":"2026-01-27T13:52:58","slug":"a-propos-de-nous","status":"publish","type":"page","link":"https:\/\/www.valide-lab.com\/fr\/a-propos-de-nous\/","title":{"rendered":"\u00c0 propos de nous"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"9665\" class=\"elementor elementor-9665 elementor-33\">\n\t\t\t\t\t\t\t        <section class=\"elementor-section elementor-top-section elementor-element elementor-element-5099d28 elementor-section-boxed elementor-section-height-default elementor-section-height-default ct-header-fixed-none ct-column-none ct-row-scroll-none ct-row-gradient--none\" data-id=\"5099d28\" data-element_type=\"section\">\n            \n                        <div class=\"elementor-container elementor-column-gap-extended \">\n                    <div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3cf6c49 ct-column-none col-offset-none\" data-id=\"3cf6c49\" data-element_type=\"column\">\n            <div class=\"elementor-widget-wrap elementor-element-populated\">\n                        \t\t<div class=\"elementor-element elementor-element-461d76b4 elementor-widget elementor-widget-ct_heading\" data-id=\"461d76b4\" data-element_type=\"widget\" data-widget_type=\"ct_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div id=\"ct_heading-461d76b4\" class=\"ct-heading h-align- item-st-default highlight-style1\">\r\n    <div class=\"ct-inline-css\"  data-css=\"\r\n                                \">\r\n    <\/div>\r\n      <div class=\"item--text-below\">\r\n      <div class=\"ct-inline-css\"  data-css=\"\r\n        \">\r\n      <\/div>\r\n          <\/div>\r\n  \r\n\t\t\t<div class=\"item--sub-title style-icon-right \" data-wow-delay=\"ms\">\r\n                        <span>\r\n                \u00c0 propos de notre soci\u00e9t\u00e9            <\/span>\r\n                            <svg class=\"svg-right\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" width=\"33\" height=\"21\" viewBox=\"0 0 33 21\">\r\n                  <defs>\r\n                    <style>\r\n                      .h-cls-1, .h-cls-2 {\r\n                        fill: none;\r\n                        stroke-width: 3px;\r\n                        fill-rule: evenodd;\r\n                      }\r\n\r\n                      .h-cls-1 {\r\n                        filter: url(#filter);\r\n                      }\r\n\r\n                      .h-cls-2 {\r\n                        filter: url(#filter-2);\r\n                      }\r\n                    <\/style>\r\n                    <filter id=\"right-h-filterct_heading-461d76b4\" x=\"-0.125\" y=\"-0.094\" width=\"32.406\" height=\"12\" filterUnits=\"userSpaceOnUse\">\r\n                      <feFlood result=\"flood\"\/>\r\n                      <feComposite result=\"composite\" operator=\"in\" in2=\"SourceGraphic\"\/>\r\n                      <feBlend result=\"blend\" in2=\"SourceGraphic\"\/>\r\n                    <\/filter>\r\n                    <filter id=\"right-h-filter-2ct_heading-461d76b4\" x=\"-10\" y=\"14.594\" width=\"29.656\" height=\"6.406\" filterUnits=\"userSpaceOnUse\">\r\n                      <feFlood result=\"flood\"\/>\r\n                      <feComposite result=\"composite\" operator=\"in\" in2=\"SourceGraphic\"\/>\r\n                      <feBlend result=\"blend\" in2=\"SourceGraphic\"\/>\r\n                    <\/filter>\r\n\r\n                    <linearGradient id=\"right-h-grad1ct_heading-461d76b4\" x1=\"0%\" y1=\"0%\" x2=\"100%\" y2=\"0%\">\r\n                      <stop offset=\"0%\" style=\"stop-color:#006cff;stop-opacity:1\" \/>\r\n                      <stop offset=\"100%\" style=\"stop-color:#1227b8;stop-opacity:1\" \/>\r\n                    <\/linearGradient>\r\n\r\n                  <\/defs>\r\n                  <g>\r\n                    <g style=\"fill: none; filter: url(#right-h-filterct_heading-461d76b4)\">\r\n                      <path id=\"right-h-pathct_heading-461d76b4\" class=\"h-cls-1\" d=\"M-0.117,8.9H27.036s5.078-3.073,0-6.517\" style=\"stroke: inherit; filter: none;\"\/>\r\n                    <\/g>\r\n                    <use xlink:href=\"#right-h-pathct_heading-461d76b4\" style=\"stroke: url(#right-h-grad1ct_heading-461d76b4); filter: none; fill: none\"\/>\r\n                    <g style=\"fill: none; filter: url(#right-h-filter-2ct_heading-461d76b4)\">\r\n                      <path id=\"right-h-bgct_heading-461d76b4\" class=\"h-cls-2\" d=\"M-9.991,14.594H17.352s5.114,3.027,0,6.422\" style=\"stroke: inherit; filter: none;\"\/>\r\n                    <\/g>\r\n                    <use xlink:href=\"#right-h-bgct_heading-461d76b4\" style=\"stroke: url(#right-h-grad1ct_heading-461d76b4); filter: none; fill: none\"\/>\r\n                  <\/g>\r\n                <\/svg>\r\n                    <\/div>\r\n\t    <h3 class=\"item--title st-default \" data-wow-delay=\"ms\">\r\n        <span class=\"ct-text-inner\">Choisissez         <cite class=\"ct-text-highlight\">\r\n            le meilleur        <\/cite>\r\n        , obtenez le meilleur<\/span>    <\/h3>\r\n<\/div>\r\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ce4e8d elementor-widget elementor-widget-ct_text_editor\" data-id=\"6ce4e8d\" data-element_type=\"widget\" data-widget_type=\"ct_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div id=\"ct_text_editor-6ce4e8d\" class=\"ct-text-editor \" data-wow-delay=\"ms\">\n\t<div class=\"ct-inline-css\"  data-css=\"\n        \t\t\">\n\n    <\/div>\n\t<div class=\"ct-text-editor elementor-clearfix\">\n\t\t<p><span style=\"font-weight: 400\">Nous avons l\u2019exp\u00e9rience et le savoir-faire pour vous guider \u00e0 travers la bureaucratie souvent d\u00e9courageante et les proc\u00e9dures \u00e9puisantes pour aller dans un nouveau pays.<\/span><\/p>\t\t\n\t<\/div>\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-92457bb elementor-widget elementor-widget-ct_tabs\" data-id=\"92457bb\" data-element_type=\"widget\" data-widget_type=\"ct_tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ct-tabs ct-tabs1  content-type-text_editor\" data-wow-delay=\"ms\">\n    <div class=\"ct-tabs--main\">\n        <div class=\"ct-tabs-title\">\n                            <span class=\"ct-tab-title active\" data-target=\"#ct_tabs-92457bb-e40f566\">\n                                                            Notre mission        \n                <\/span>\n                            <span class=\"ct-tab-title \" data-target=\"#ct_tabs-92457bb-3082b60\">\n                                                            Notre vision        \n                <\/span>\n                            <span class=\"ct-tab-title \" data-target=\"#ct_tabs-92457bb-7311b88\">\n                                                            Nos valeurs        \n                <\/span>\n                    <\/div>\n\n        <div class=\"ct-tabs-content\">\n                            <div class=\"ct-tab-content \" id=\"ct_tabs-92457bb-e40f566\" style=\"display:block;\"><p><span style=\"font-weight: 400;\">Depuis 2016, nous avons soutenu nos clients, particuliers et entreprises, avec une assistance administrative au sens large.<\/span><\/p><p><span style=\"font-weight: 400;\">Nous avons vu les pays que nous couvrons passer d\u2019un seul \u00e0 sept \u00e0 pr\u00e9sent, couvrant tout, de l\u2019immigration \u00e0 la cr\u00e9ation d\u2019une entreprise.<\/span><\/p><\/div>\n                            <div class=\"ct-tab-content \" id=\"ct_tabs-92457bb-3082b60\"><p><span style=\"font-weight: 400;\">Notre vocation est de guider et d\u2019informer nos clients dans toutes leurs d\u00e9marches. Nous sommes l\u00e0 pour les aider \u00e0 s\u2019orienter avec succ\u00e8s et \u00e0 changer de vie, \u00e0 faire face \u00e0 des difficult\u00e9s inattendues, mais aussi pour leur permettre de b\u00e9n\u00e9ficier des nombreux syst\u00e8mes sociaux existants auxquels ils ont droit sans m\u00eame le savoir.<\/span><\/p><\/div>\n                            <div class=\"ct-tab-content \" id=\"ct_tabs-92457bb-7311b88\"><p><span style=\"font-weight: 400;\">Nous valorisons la clart\u00e9 et la simplicit\u00e9. Nous savons combien il peut \u00eatre difficile de repartir \u00e0 z\u00e9ro. Nous voulons donc le rendre aussi facile et sans stress que possible\u2009!<\/span><\/p><\/div>\n                    <\/div>\n    <\/div>\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\n        <\/div>\n                <div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-244f4bd ct-column-none col-offset-none\" data-id=\"244f4bd\" data-element_type=\"column\">\n            <div class=\"elementor-widget-wrap elementor-element-populated\">\n                        \t\t<div class=\"elementor-element elementor-element-9977bd5 elementor-widget elementor-widget-ct_banner\" data-id=\"9977bd5\" data-element_type=\"widget\" data-widget_type=\"ct_banner.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t<div class=\"ct-banner ct-banner1 \" data-wow-delay=\"ms\">\r\n\t\t<div class=\"ct-banner-inner\">\r\n\t\t\t<div class=\"ct-banner-image\">\r\n\t\t\t\t<img decoding=\"async\" class=\"\" src=\"https:\/\/www.valide-lab.com\/wp-content\/uploads\/2022\/09\/pexels-pixabay-163064-scaled-800x530.jpg\" width=\"800\" height=\"530\" alt=\"pexels-pixabay-163064\" title=\"pexels-pixabay-163064\" \/>\t\t\t\t\t\t\t\t\t<div class=\"ct-banner-counter\">\r\n\t\t\t\t\t\t<div class=\"ct-counter-inner\">\r\n\t\t\t\t\t\t\t<div class=\"ct-counter-number-value\" data-duration=\"2000\" data-to-value=\"8\" data-delimiter=\"\"><\/div>\r\n\t\t\t\t\t\t\t<div class=\"ct-counter-title el-empty\">ans d\u2019exp\u00e9rience et de succ\u00e8s<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<div class=\"ct-banner-holder\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"item--icon el-empty\">\r\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-globe\"><\/i>\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"ct-banner-meta\">\r\n\t\t\t\t\t<h5 class=\"item--title el-empty\">Nous avons un vaste r\u00e9seau de professionnels \u00e0 votre disposition.<\/h5>\r\n\t\t\t\t\t<div class=\"item--desc el-empty\">Nous pouvons vous aider sur une vari\u00e9t\u00e9 de services li\u00e9s \u00e0 l\u2019immigration et au travail dans un nouveau pays. Veuillez consulter les pays dans lesquels nous offrons nos services.<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t\t<\/div>\r\n\t<\/div>\r\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\n        <\/div>\n                            <\/div>\n        <\/section>\n                <section class=\"elementor-section elementor-top-section elementor-element elementor-element-371695e elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default ct-header-fixed-none ct-column-none ct-row-scroll-none ct-row-gradient--none\" data-id=\"371695e\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n            \n                        <div class=\"elementor-container elementor-column-gap-extended \">\n                    <div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-84fdb13 ct-column-none col-offset-none\" data-id=\"84fdb13\" data-element_type=\"column\">\n            <div class=\"elementor-widget-wrap elementor-element-populated\">\n                        \t\t<div class=\"elementor-element elementor-element-8f5f31e elementor-widget elementor-widget-ct_history\" data-id=\"8f5f31e\" data-element_type=\"widget\" data-widget_type=\"ct_history.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t    <div class=\"ct-history ct-history-carousel1 ct-slick-slider\">\r\n        <div class=\"ct-carousel-inner\">\r\n            <div class=\"ct-slick-carousel\" data-arrows=\"true\" data-dots=\"\" data-pauseOnHover=\"\" data-autoplay=\"\" data-autoplaySpeed=\"5000\" data-infinite=\"true\" data-speed=\"500\" data-colxs=\"1\" data-colsm=\"2\" data-colmd=\"3\" data-collg=\"4\" data-colxl=\"4\" data-dir=\"false\" data-slidesToScroll=\"1\">\r\n                                        <div class=\"slick-slide\">\r\n                            <div id=\"ct_history-8f5f31e0\" class=\"item--inner wow flipInY\">\r\n                                <div class=\"ct-inline-css\"  data-css=\"\r\n                                                                            .ct-history #ct_history-8f5f31e0 .item--year {\r\n                                            background-color: #00C6FF;\r\n                                        }\r\n                                        .ct-history #ct_history-8f5f31e0 .item--year:before {\r\n                                            border-color: transparent transparent transparent #00C6FF;\r\n                                        }\r\n                                        .ct-history #ct_history-8f5f31e0 .item--year span:before {\r\n                                            border-color: #00C6FF #00C6FF transparent transparent;\r\n                                        }\r\n                                        .ct-history #ct_history-8f5f31e0 .item--year span:after {\r\n                                            border-color: transparent #00C6FF #00C6FF transparent;\r\n                                        }\r\n                                    \">\r\n                                <\/div>\r\n                                                                    <div class=\"item--image\">\r\n                                        <div class=\"item--mask bg-image\" style=\"background-image: url(https:\/\/www.valide-lab.com\/wp-content\/uploads\/2022\/09\/mikhail-luxkstn-T6E11THRacc-unsplash-scaled.jpg);\"><\/div>\r\n                                    <\/div>\r\n                                                                <div class=\"item--holder\">\r\n                                    <div class=\"item--year\">\r\n                                        <span>2016<\/span>\r\n                                    <\/div>\r\n                                    <h3 class=\"item--title\">    \r\n                                        Bulgarie                                    <\/h3>\r\n                                    <div class=\"item--description\">Nous avons commenc\u00e9 notre entreprise en nous concentrant sur la Bulgarie en aidant nos clients pour tout, des questions d\u2019immigration \u00e0 l\u2019assistance administrative.<\/div>\r\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                                        <div class=\"slick-slide\">\r\n                            <div id=\"ct_history-8f5f31e1\" class=\"item--inner wow flipInY\">\r\n                                <div class=\"ct-inline-css\"  data-css=\"\r\n                                                                            .ct-history #ct_history-8f5f31e1 .item--year {\r\n                                            background-color: #2093FF;\r\n                                        }\r\n                                        .ct-history #ct_history-8f5f31e1 .item--year:before {\r\n                                            border-color: transparent transparent transparent #2093FF;\r\n                                        }\r\n                                        .ct-history #ct_history-8f5f31e1 .item--year span:before {\r\n                                            border-color: #2093FF #2093FF transparent transparent;\r\n                                        }\r\n                                        .ct-history #ct_history-8f5f31e1 .item--year span:after {\r\n                                            border-color: transparent #2093FF #2093FF transparent;\r\n                                        }\r\n                                    \">\r\n                                <\/div>\r\n                                                                    <div class=\"item--image\">\r\n                                        <div class=\"item--mask bg-image\" style=\"background-image: url(https:\/\/www.valide-lab.com\/wp-content\/uploads\/2022\/09\/pexels-danne-457563.jpg);\"><\/div>\r\n                                    <\/div>\r\n                                                                <div class=\"item--holder\">\r\n                                    <div class=\"item--year\">\r\n                                        <span>2017<\/span>\r\n                                    <\/div>\r\n                                    <h3 class=\"item--title\">    \r\n                                        USA                                    <\/h3>\r\n                                    <div class=\"item--description\">Les \u00c9tats-Unis sont venus ensuite. Nous nous sommes d\u00e9velopp\u00e9s facilement avec l\u2019aide de nos partenaires am\u00e9ricains. Nous avons offert nos services d\u2019immigration et de visa de travail.<\/div>\r\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                                        <div class=\"slick-slide\">\r\n                            <div id=\"ct_history-8f5f31e2\" class=\"item--inner wow flipInY\">\r\n                                <div class=\"ct-inline-css\"  data-css=\"\r\n                                                                            .ct-history #ct_history-8f5f31e2 .item--year {\r\n                                            background-color: #0D5BEE;\r\n                                        }\r\n                                        .ct-history #ct_history-8f5f31e2 .item--year:before {\r\n                                            border-color: transparent transparent transparent #0D5BEE;\r\n                                        }\r\n                                        .ct-history #ct_history-8f5f31e2 .item--year span:before {\r\n                                            border-color: #0D5BEE #0D5BEE transparent transparent;\r\n                                        }\r\n                                        .ct-history #ct_history-8f5f31e2 .item--year span:after {\r\n                                            border-color: transparent #0D5BEE #0D5BEE transparent;\r\n                                        }\r\n                                    \">\r\n                                <\/div>\r\n                                                                    <div class=\"item--image\">\r\n                                        <div class=\"item--mask bg-image\" style=\"background-image: url(https:\/\/www.valide-lab.com\/wp-content\/uploads\/2022\/09\/pexels-shahbaz-zaman-11184234-scaled.jpg);\"><\/div>\r\n                                    <\/div>\r\n                                                                <div class=\"item--holder\">\r\n                                    <div class=\"item--year\">\r\n                                        <span>2018<\/span>\r\n                                    <\/div>\r\n                                    <h3 class=\"item--title\">    \r\n                                        Canada                                    <\/h3>\r\n                                    <div class=\"item--description\">Apr\u00e8s les \u00c9tats-Unis, nous avons poursuivi notre expansion nord-am\u00e9ricaine avec le Canada et avons consid\u00e9rablement augment\u00e9 nos capacit\u00e9s et notre exp\u00e9rience.<\/div>\r\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                                        <div class=\"slick-slide\">\r\n                            <div id=\"ct_history-8f5f31e3\" class=\"item--inner wow flipInY\">\r\n                                <div class=\"ct-inline-css\"  data-css=\"\r\n                                                                            .ct-history #ct_history-8f5f31e3 .item--year {\r\n                                            background-color: #0925AA;\r\n                                        }\r\n                                        .ct-history #ct_history-8f5f31e3 .item--year:before {\r\n                                            border-color: transparent transparent transparent #0925AA;\r\n                                        }\r\n                                        .ct-history #ct_history-8f5f31e3 .item--year span:before {\r\n                                            border-color: #0925AA #0925AA transparent transparent;\r\n                                        }\r\n                                        .ct-history #ct_history-8f5f31e3 .item--year span:after {\r\n                                            border-color: transparent #0925AA #0925AA transparent;\r\n                                        }\r\n                                    \">\r\n                                <\/div>\r\n                                                                    <div class=\"item--image\">\r\n                                        <div class=\"item--mask bg-image\" style=\"background-image: url(https:\/\/www.valide-lab.com\/wp-content\/uploads\/2022\/09\/pexels-vectors-icon-968311-scaled.jpg);\"><\/div>\r\n                                    <\/div>\r\n                                                                <div class=\"item--holder\">\r\n                                    <div class=\"item--year\">\r\n                                        <span>2019<\/span>\r\n                                    <\/div>\r\n                                    <h3 class=\"item--title\">    \r\n                                        Australie                                    <\/h3>\r\n                                    <div class=\"item--description\">Notre prochain pays anglophone a \u00e9t\u00e9 l\u2019Australie. C\u2019\u00e9tait une suite naturelle et son ajout a \u00e9t\u00e9 une belle r\u00e9alisation, nous sommes fiers d\u2019y \u00eatre pr\u00e9sents.<\/div>\r\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                                        <div class=\"slick-slide\">\r\n                            <div id=\"ct_history-8f5f31e4\" class=\"item--inner wow flipInY\">\r\n                                <div class=\"ct-inline-css\"  data-css=\"\r\n                                                                            .ct-history #ct_history-8f5f31e4 .item--year {\r\n                                            background-color: #00C6FF;\r\n                                        }\r\n                                        .ct-history #ct_history-8f5f31e4 .item--year:before {\r\n                                            border-color: transparent transparent transparent #00C6FF;\r\n                                        }\r\n                                        .ct-history #ct_history-8f5f31e4 .item--year span:before {\r\n                                            border-color: #00C6FF #00C6FF transparent transparent;\r\n                                        }\r\n                                        .ct-history #ct_history-8f5f31e4 .item--year span:after {\r\n                                            border-color: transparent #00C6FF #00C6FF transparent;\r\n                                        }\r\n                                    \">\r\n                                <\/div>\r\n                                                                    <div class=\"item--image\">\r\n                                        <div class=\"item--mask bg-image\" style=\"background-image: url(https:\/\/www.valide-lab.com\/wp-content\/uploads\/2022\/09\/pexels-bernadett-varga-4449834-scaled.jpg);\"><\/div>\r\n                                    <\/div>\r\n                                                                <div class=\"item--holder\">\r\n                                    <div class=\"item--year\">\r\n                                        <span>2020<\/span>\r\n                                    <\/div>\r\n                                    <h3 class=\"item--title\">    \r\n                                        Le Royaume-Uni                                    <\/h3>\r\n                                    <div class=\"item--description\">Nous nous sommes lanc\u00e9s avec toute notre \u00e9nergie dans le Royaume-Uni, malgr\u00e9 les complications accrues du Brexit. Nous avons relev\u00e9 le d\u00e9fi et nous avons r\u00e9ussi !<\/div>\r\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                                        <div class=\"slick-slide\">\r\n                            <div id=\"ct_history-8f5f31e5\" class=\"item--inner wow flipInY\">\r\n                                <div class=\"ct-inline-css\"  data-css=\"\r\n                                                                            .ct-history #ct_history-8f5f31e5 .item--year {\r\n                                            background-color: #2093FF;\r\n                                        }\r\n                                        .ct-history #ct_history-8f5f31e5 .item--year:before {\r\n                                            border-color: transparent transparent transparent #2093FF;\r\n                                        }\r\n                                        .ct-history #ct_history-8f5f31e5 .item--year span:before {\r\n                                            border-color: #2093FF #2093FF transparent transparent;\r\n                                        }\r\n                                        .ct-history #ct_history-8f5f31e5 .item--year span:after {\r\n                                            border-color: transparent #2093FF #2093FF transparent;\r\n                                        }\r\n                                    \">\r\n                                <\/div>\r\n                                                                    <div class=\"item--image\">\r\n                                        <div class=\"item--mask bg-image\" style=\"background-image: url(https:\/\/www.valide-lab.com\/wp-content\/uploads\/2022\/09\/pexels-mathias-reding-12467785-scaled.jpg);\"><\/div>\r\n                                    <\/div>\r\n                                                                <div class=\"item--holder\">\r\n                                    <div class=\"item--year\">\r\n                                        <span>2021<\/span>\r\n                                    <\/div>\r\n                                    <h3 class=\"item--title\">    \r\n                                        France                                    <\/h3>\r\n                                    <div class=\"item--description\">Nous sommes entr\u00e9s en France non seulement avec nos services d\u2019immigration habituels, mais aussi avec une assistance pour obtenir les avantages offerts par les nombreux programmes sociaux.<\/div>\r\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                                        <div class=\"slick-slide\">\r\n                            <div id=\"ct_history-8f5f31e6\" class=\"item--inner wow flipInY\">\r\n                                <div class=\"ct-inline-css\"  data-css=\"\r\n                                    \">\r\n                                <\/div>\r\n                                                                    <div class=\"item--image\">\r\n                                        <div class=\"item--mask bg-image\" style=\"background-image: url(https:\/\/www.valide-lab.com\/wp-content\/uploads\/2022\/09\/jametlene-reskp-uoAs88xAnT8-unsplash-scaled.jpg);\"><\/div>\r\n                                    <\/div>\r\n                                                                <div class=\"item--holder\">\r\n                                    <div class=\"item--year\">\r\n                                        <span>2024<\/span>\r\n                                    <\/div>\r\n                                    <h3 class=\"item--title\">    \r\n                                        Italie                                    <\/h3>\r\n                                    <div class=\"item--description\">Notre dernier projet concerne le syst\u00e8me de documentation italien, o\u00f9 nous serons bient\u00f4t en mesure d&#039;offrir nos services \u00e0 ceux qui recherchent des informations sp\u00e9cifiques allant du bilan financier d&#039;une entreprise \u00e0 l&#039;historique de l&#039;immatriculation d&#039;un v\u00e9hicule.<\/div>\r\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\n        <\/div>\n                            <\/div>\n        <\/section>\n        \t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u00c0 propos de notre soci\u00e9t\u00e9 Choisissez le meilleur , obtenez le meilleur Nous avons l\u2019exp\u00e9rience et le savoir-faire pour vous guider \u00e0 travers la bureaucratie souvent d\u00e9courageante et les proc\u00e9dures \u00e9puisantes pour aller dans un nouveau pays. Notre mission Notre vision Nos valeurs Depuis 2016, nous avons soutenu nos clients, particuliers et entreprises, avec une [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-9665","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.valide-lab.com\/fr\/wp-json\/wp\/v2\/pages\/9665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.valide-lab.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.valide-lab.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.valide-lab.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.valide-lab.com\/fr\/wp-json\/wp\/v2\/comments?post=9665"}],"version-history":[{"count":23,"href":"https:\/\/www.valide-lab.com\/fr\/wp-json\/wp\/v2\/pages\/9665\/revisions"}],"predecessor-version":[{"id":15650,"href":"https:\/\/www.valide-lab.com\/fr\/wp-json\/wp\/v2\/pages\/9665\/revisions\/15650"}],"wp:attachment":[{"href":"https:\/\/www.valide-lab.com\/fr\/wp-json\/wp\/v2\/media?parent=9665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}